{"id":65,"count":1,"description":"","link":"https:\/\/alcapones.com\/blog\/category\/other-miscellaneous\/orlando-local-gripes","name":"Orlando Local Gripes","slug":"orlando-local-gripes","taxonomy":"category","parent":55,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Orlando Local Gripes Archives - Al&#039;s Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alcapones.com\/blog\/category\/other-miscellaneous\/orlando-local-gripes\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Orlando Local Gripes Archives - Al&#039;s Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alcapones.com\/blog\/category\/other-miscellaneous\/orlando-local-gripes\" \/>\n<meta property=\"og:site_name\" content=\"Advice You Can&#039;t Refuse\" \/>\n<meta property=\"og:image\" content=\"https:\/\/alcapones.com\/blog\/wp-content\/uploads\/2021\/08\/Capones-OG-promo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@AlcaponesShow\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/alcapones.com\\\/blog\\\/category\\\/other-miscellaneous\\\/orlando-local-gripes\",\"url\":\"https:\\\/\\\/alcapones.com\\\/blog\\\/category\\\/other-miscellaneous\\\/orlando-local-gripes\",\"name\":\"Orlando Local Gripes Archives - Al's Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alcapones.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alcapones.com\\\/blog\\\/category\\\/other-miscellaneous\\\/orlando-local-gripes#breadcrumb\"},\"inLanguage\":\"en\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alcapones.com\\\/blog\\\/category\\\/other-miscellaneous\\\/orlando-local-gripes#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/alcapones.com\\\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Orlando: Other Side\",\"item\":\"https:\\\/\\\/alcapones.com\\\/blog\\\/category\\\/other-miscellaneous\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Orlando Local Gripes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alcapones.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/alcapones.com\\\/blog\\\/\",\"name\":\"Advice You Can't Refuse\",\"description\":\"from the Wise Guys at AlCapones.com\",\"publisher\":{\"@id\":\"https:\\\/\\\/alcapones.com\\\/blog\\\/#organization\"},\"alternateName\":\"Al's Blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alcapones.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/alcapones.com\\\/blog\\\/#organization\",\"name\":\"Capone's Dinner & Show\",\"url\":\"https:\\\/\\\/alcapones.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"https:\\\/\\\/alcapones.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/alcapones.com\\\/blog\\\/wp-content\\\/uploads\\\/capones-icon.png\",\"contentUrl\":\"https:\\\/\\\/alcapones.com\\\/blog\\\/wp-content\\\/uploads\\\/capones-icon.png\",\"width\":158,\"height\":158,\"caption\":\"Capone's Dinner & Show\"},\"image\":{\"@id\":\"https:\\\/\\\/alcapones.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Caponesdinnershow\",\"https:\\\/\\\/x.com\\\/AlcaponesShow\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Orlando Local Gripes Archives - Al's Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alcapones.com\/blog\/category\/other-miscellaneous\/orlando-local-gripes","og_locale":"en_US","og_type":"article","og_title":"Orlando Local Gripes Archives - Al's Blog","og_url":"https:\/\/alcapones.com\/blog\/category\/other-miscellaneous\/orlando-local-gripes","og_site_name":"Advice You Can't Refuse","og_image":[{"width":1200,"height":630,"url":"https:\/\/alcapones.com\/blog\/wp-content\/uploads\/2021\/08\/Capones-OG-promo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@AlcaponesShow","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/alcapones.com\/blog\/category\/other-miscellaneous\/orlando-local-gripes","url":"https:\/\/alcapones.com\/blog\/category\/other-miscellaneous\/orlando-local-gripes","name":"Orlando Local Gripes Archives - Al's Blog","isPartOf":{"@id":"https:\/\/alcapones.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/alcapones.com\/blog\/category\/other-miscellaneous\/orlando-local-gripes#breadcrumb"},"inLanguage":"en"},{"@type":"BreadcrumbList","@id":"https:\/\/alcapones.com\/blog\/category\/other-miscellaneous\/orlando-local-gripes#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/alcapones.com\/blog"},{"@type":"ListItem","position":2,"name":"Orlando: Other Side","item":"https:\/\/alcapones.com\/blog\/category\/other-miscellaneous"},{"@type":"ListItem","position":3,"name":"Orlando Local Gripes"}]},{"@type":"WebSite","@id":"https:\/\/alcapones.com\/blog\/#website","url":"https:\/\/alcapones.com\/blog\/","name":"Advice You Can't Refuse","description":"from the Wise Guys at AlCapones.com","publisher":{"@id":"https:\/\/alcapones.com\/blog\/#organization"},"alternateName":"Al's Blog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alcapones.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en"},{"@type":"Organization","@id":"https:\/\/alcapones.com\/blog\/#organization","name":"Capone's Dinner & Show","url":"https:\/\/alcapones.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en","@id":"https:\/\/alcapones.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/alcapones.com\/blog\/wp-content\/uploads\/capones-icon.png","contentUrl":"https:\/\/alcapones.com\/blog\/wp-content\/uploads\/capones-icon.png","width":158,"height":158,"caption":"Capone's Dinner & Show"},"image":{"@id":"https:\/\/alcapones.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Caponesdinnershow","https:\/\/x.com\/AlcaponesShow"]}]}},"_links":{"self":[{"href":"https:\/\/alcapones.com\/blog\/wp-json\/wp\/v2\/categories\/65","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alcapones.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/alcapones.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/alcapones.com\/blog\/wp-json\/wp\/v2\/categories\/55"}],"wp:post_type":[{"href":"https:\/\/alcapones.com\/blog\/wp-json\/wp\/v2\/posts?categories=65"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}